{"id":6068,"date":"2017-11-28T17:33:22","date_gmt":"2017-11-28T22:33:22","guid":{"rendered":"https:\/\/medisafeapp.wpengine.com\/giveaway-share-the-app-save-a-life\/"},"modified":"2022-11-21T10:46:38","modified_gmt":"2022-11-21T15:46:38","slug":"giveaway-share-the-app-save-a-life","status":"publish","type":"post","link":"https:\/\/medisafeapp.com\/ru\/giveaway-share-the-app-save-a-life\/","title":{"rendered":"Giveaway: Share the App. Save a Life."},"content":{"rendered":"<p>Hey Medisafers,<br \/>\nIt&#8217;s #GivingTuesday and we&#8217;re upping our game. Starting today (Nov 28) and through January 2, 2018, you have the chance to give one of your loved ones the chance to win a brand new phone!<br \/>\nHow do you get them entered?<\/p>\n<ol>\n<li>Head to our <a href=\"https:\/\/www.facebook.com\/MedisafeProject\/\">Facebook page<\/a>\u00a0or directly to our <a href=\"https:\/\/www.facebook.com\/111249148927499\/app\/190076381016644\/?app_data=%7B%7D\">Contest Page<\/a><\/li>\n<li>Enter the giveaway<\/li>\n<li>Tag anyone you know, friends or family, who might need a little Medisafe in their lives<\/li>\n<li>Stay tuned for the winners!<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hey Medisafers, It&#8217;s #GivingTuesday and we&#8217;re upping our game. Starting today (Nov 28) and through January 2, 2018, you have the chance to give one of your loved ones the chance to win a brand new phone! How do you get them entered? Head to our Facebook page\u00a0or directly to our Contest Page Enter the&hellip;<\/p>\n","protected":false},"author":2,"featured_media":6069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giveaway: Share the App. Save a Life. - MedisafeApp<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medisafeapp.com\/ru\/giveaway-share-the-app-save-a-life\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giveaway: Share the App. Save a Life. - MedisafeApp\" \/>\n<meta property=\"og:description\" content=\"Hey Medisafers, It&#8217;s #GivingTuesday and we&#8217;re upping our game. Starting today (Nov 28) and through January 2, 2018, you have the chance to give one of your loved ones the chance to win a brand new phone! How do you get them entered? Head to our Facebook page\u00a0or directly to our Contest Page Enter the&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medisafeapp.com\/ru\/giveaway-share-the-app-save-a-life\/\" \/>\n<meta property=\"og:site_name\" content=\"MedisafeApp\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-28T22:33:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-21T15:46:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medisafeapp.com\/wp-content\/uploads\/2022\/10\/MomReviewGrey-1080x1080-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bryan Barrera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bryan Barrera\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medisafeapp.com\\\/giveaway-share-the-app-save-a-life\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medisafeapp.com\\\/giveaway-share-the-app-save-a-life\\\/\"},\"author\":{\"name\":\"Bryan Barrera\",\"@id\":\"https:\\\/\\\/medisafeapp.com\\\/#\\\/schema\\\/person\\\/f626cfc050e00a61dd824dd5ab3091ae\"},\"headline\":\"Giveaway: Share the App. Save a Life.\",\"datePublished\":\"2017-11-28T22:33:22+00:00\",\"dateModified\":\"2022-11-21T15:46:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medisafeapp.com\\\/giveaway-share-the-app-save-a-life\\\/\"},\"wordCount\":85,\"image\":{\"@id\":\"https:\\\/\\\/medisafeapp.com\\\/giveaway-share-the-app-save-a-life\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medisafeapp.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/MomReviewGrey-1080x1080-1.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"ru-RU\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/medisafeapp.com\\\/ru\\\/giveaway-share-the-app-save-a-life\\\/\",\"url\":\"https:\\\/\\\/medisafeapp.com\\\/ru\\\/giveaway-share-the-app-save-a-life\\\/\",\"name\":\"Giveaway: Share the App. Save a Life. - MedisafeApp\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medisafeapp.com\\\/ru\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/medisafeapp.com\\\/ru\\\/giveaway-share-the-app-save-a-life\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/medisafeapp.com\\\/giveaway-share-the-app-save-a-life\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medisafeapp.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/MomReviewGrey-1080x1080-1.jpg\",\"datePublished\":\"2017-11-28T22:33:22+00:00\",\"dateModified\":\"2022-11-21T15:46:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/medisafeapp.com\\\/#\\\/schema\\\/person\\\/f626cfc050e00a61dd824dd5ab3091ae\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medisafeapp.com\\\/ru\\\/giveaway-share-the-app-save-a-life\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/medisafeapp.com\\\/ru\\\/giveaway-share-the-app-save-a-life\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/medisafeapp.com\\\/ru\\\/giveaway-share-the-app-save-a-life\\\/#primaryimage\",\"url\":\"https:\\\/\\\/medisafeapp.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/MomReviewGrey-1080x1080-1.jpg\",\"contentUrl\":\"https:\\\/\\\/medisafeapp.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/MomReviewGrey-1080x1080-1.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medisafeapp.com\\\/ru\\\/giveaway-share-the-app-save-a-life\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/medisafeapp.com\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giveaway: Share the App. Save a Life.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medisafeapp.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/medisafeapp.com\\\/ru\\\/\",\"name\":\"MedisafeApp\",\"description\":\"(English) \",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medisafeapp.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medisafeapp.com\\\/#\\\/schema\\\/person\\\/f626cfc050e00a61dd824dd5ab3091ae\",\"name\":\"Bryan Barrera\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e600cc6a75a64997ef84ecedf85d01c3409b7254a630003bda046c939538ae40?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e600cc6a75a64997ef84ecedf85d01c3409b7254a630003bda046c939538ae40?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e600cc6a75a64997ef84ecedf85d01c3409b7254a630003bda046c939538ae40?s=96&d=mm&r=g\",\"caption\":\"Bryan Barrera\"},\"url\":\"https:\\\/\\\/medisafeapp.com\\\/ru\\\/author\\\/bryanconsensusinteractive-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giveaway: Share the App. Save a Life. - MedisafeApp","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medisafeapp.com\/ru\/giveaway-share-the-app-save-a-life\/","og_locale":"ru_RU","og_type":"article","og_title":"Giveaway: Share the App. Save a Life. - MedisafeApp","og_description":"Hey Medisafers, It&#8217;s #GivingTuesday and we&#8217;re upping our game. Starting today (Nov 28) and through January 2, 2018, you have the chance to give one of your loved ones the chance to win a brand new phone! How do you get them entered? Head to our Facebook page\u00a0or directly to our Contest Page Enter the&hellip;","og_url":"https:\/\/medisafeapp.com\/ru\/giveaway-share-the-app-save-a-life\/","og_site_name":"MedisafeApp","article_published_time":"2017-11-28T22:33:22+00:00","article_modified_time":"2022-11-21T15:46:38+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/medisafeapp.com\/wp-content\/uploads\/2022\/10\/MomReviewGrey-1080x1080-1.jpg","type":"image\/jpeg"}],"author":"Bryan Barrera","twitter_card":"summary_large_image","twitter_misc":{"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c":"Bryan Barrera"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medisafeapp.com\/giveaway-share-the-app-save-a-life\/#article","isPartOf":{"@id":"https:\/\/medisafeapp.com\/giveaway-share-the-app-save-a-life\/"},"author":{"name":"Bryan Barrera","@id":"https:\/\/medisafeapp.com\/#\/schema\/person\/f626cfc050e00a61dd824dd5ab3091ae"},"headline":"Giveaway: Share the App. Save a Life.","datePublished":"2017-11-28T22:33:22+00:00","dateModified":"2022-11-21T15:46:38+00:00","mainEntityOfPage":{"@id":"https:\/\/medisafeapp.com\/giveaway-share-the-app-save-a-life\/"},"wordCount":85,"image":{"@id":"https:\/\/medisafeapp.com\/giveaway-share-the-app-save-a-life\/#primaryimage"},"thumbnailUrl":"https:\/\/medisafeapp.com\/wp-content\/uploads\/2022\/10\/MomReviewGrey-1080x1080-1.jpg","articleSection":["Uncategorized"],"inLanguage":"ru-RU"},{"@type":"WebPage","@id":"https:\/\/medisafeapp.com\/ru\/giveaway-share-the-app-save-a-life\/","url":"https:\/\/medisafeapp.com\/ru\/giveaway-share-the-app-save-a-life\/","name":"Giveaway: Share the App. Save a Life. - MedisafeApp","isPartOf":{"@id":"https:\/\/medisafeapp.com\/ru\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medisafeapp.com\/ru\/giveaway-share-the-app-save-a-life\/#primaryimage"},"image":{"@id":"https:\/\/medisafeapp.com\/giveaway-share-the-app-save-a-life\/#primaryimage"},"thumbnailUrl":"https:\/\/medisafeapp.com\/wp-content\/uploads\/2022\/10\/MomReviewGrey-1080x1080-1.jpg","datePublished":"2017-11-28T22:33:22+00:00","dateModified":"2022-11-21T15:46:38+00:00","author":{"@id":"https:\/\/medisafeapp.com\/#\/schema\/person\/f626cfc050e00a61dd824dd5ab3091ae"},"breadcrumb":{"@id":"https:\/\/medisafeapp.com\/ru\/giveaway-share-the-app-save-a-life\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/medisafeapp.com\/ru\/giveaway-share-the-app-save-a-life\/"]]}]},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/medisafeapp.com\/ru\/giveaway-share-the-app-save-a-life\/#primaryimage","url":"https:\/\/medisafeapp.com\/wp-content\/uploads\/2022\/10\/MomReviewGrey-1080x1080-1.jpg","contentUrl":"https:\/\/medisafeapp.com\/wp-content\/uploads\/2022\/10\/MomReviewGrey-1080x1080-1.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/medisafeapp.com\/ru\/giveaway-share-the-app-save-a-life\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/medisafeapp.com\/ru\/"},{"@type":"ListItem","position":2,"name":"Giveaway: Share the App. Save a Life."}]},{"@type":"WebSite","@id":"https:\/\/medisafeapp.com\/ru\/#website","url":"https:\/\/medisafeapp.com\/ru\/","name":"MedisafeApp","description":"(English) ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medisafeapp.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Person","@id":"https:\/\/medisafeapp.com\/#\/schema\/person\/f626cfc050e00a61dd824dd5ab3091ae","name":"Bryan Barrera","image":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/secure.gravatar.com\/avatar\/e600cc6a75a64997ef84ecedf85d01c3409b7254a630003bda046c939538ae40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e600cc6a75a64997ef84ecedf85d01c3409b7254a630003bda046c939538ae40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e600cc6a75a64997ef84ecedf85d01c3409b7254a630003bda046c939538ae40?s=96&d=mm&r=g","caption":"Bryan Barrera"},"url":"https:\/\/medisafeapp.com\/ru\/author\/bryanconsensusinteractive-com\/"}]}},"_links":{"self":[{"href":"https:\/\/medisafeapp.com\/ru\/wp-json\/wp\/v2\/posts\/6068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medisafeapp.com\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medisafeapp.com\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medisafeapp.com\/ru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/medisafeapp.com\/ru\/wp-json\/wp\/v2\/comments?post=6068"}],"version-history":[{"count":0,"href":"https:\/\/medisafeapp.com\/ru\/wp-json\/wp\/v2\/posts\/6068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medisafeapp.com\/ru\/wp-json\/wp\/v2\/media\/6069"}],"wp:attachment":[{"href":"https:\/\/medisafeapp.com\/ru\/wp-json\/wp\/v2\/media?parent=6068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medisafeapp.com\/ru\/wp-json\/wp\/v2\/categories?post=6068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medisafeapp.com\/ru\/wp-json\/wp\/v2\/tags?post=6068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}